{"id":1803,"date":"2022-03-08T10:14:43","date_gmt":"2022-03-08T10:14:43","guid":{"rendered":"https:\/\/themexriver.com\/glow-demo\/?page_id=1803"},"modified":"2024-03-06T03:03:08","modified_gmt":"2024-03-06T03:03:08","slug":"about-insurance-style","status":"publish","type":"page","link":"https:\/\/kferfseguros.com.br\/index.php\/about-insurance-style\/","title":{"rendered":"Sobre N\u00f3s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1803\" class=\"elementor elementor-1803\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f54e62 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6f54e62\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-424407e\" data-id=\"424407e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b26e94 elementor-widget elementor-widget-glow-about-v3\" data-id=\"8b26e94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glow-about-v3.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <!-- Start of about section\r\n        ============================================= -->\r\n        <section id=\"gl-about-3\" class=\"gl-about-section-3 position-relative\">\r\n            <div class=\"container\">\r\n                <div class=\"gl-about-content-3 position-relative\">\r\n                    <div class=\"row d-flex align-items-center\">\r\n                        <div class=\"col-lg-6\">\r\n                            <div class=\"gl-about-img-wrapper-3 position-relative\">\r\n                                                                    <div class=\"gl-about-img-3\">\r\n                                        <img decoding=\"async\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/foto-2-de-sala-comercial-para-alugar-35m-em-paraiso-sao-paulo.jpg\" alt=\"\">\r\n                                    <\/div>\r\n                                \r\n                                                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"col-lg-6\">\r\n                            <div class=\"gl-about-text-3 headline-3 pera-content\">\r\n                                <div class=\"gl-section-title-3\">\r\n                                                                            <div class=\"subtitle\">Sobre N\u00f3s<\/div>\r\n                                                                                                                <h2>Nossa Historia                                                                                        <span>KF&amp;RF Seguros<\/span><\/h2>\r\n                                                                                                                                                                        <p>A KF &amp; RF Seguros surgiu da uni\u00e3o de profissionais com 18 anos de experi\u00eancia no setor. Nossos fundadores possuem s\u00f3lida viv\u00eancia no mercado financeiro, com passagens por renomados bancos e seguradoras. \n<\/p>\r\n                                                                            <\/div>\r\n                                    <div class=\"gl-about-feature-list-3 ul-li-block\">\r\n                                           \r\n                                            <ul>\r\n                                                                                                    <li><i class=\"flaticon-draw-check-mark\"><\/i>\u00c1rea Juridica, contamos com uma especialista jur\u00eddica dedicada ao planejamento sucess\u00f3rio e compliance empresarial, o que se torna um diferencial fundamental em todos os aspectos da consultoria prestada pela Corretora.<\/li>\r\n                                                                                                    <li><i class=\"flaticon-draw-check-mark\"><\/i>Nossa miss\u00e3o \u00e9 proporcionar a melhor experi\u00eancia aos clientes, destacando-nos pelo atendimento consultivo e personalizado que oferecemos.<\/li>\r\n                                                                                                    <li><i class=\"flaticon-draw-check-mark\"><\/i>Trabalhamos com as mais renomadas Seguradoras do Brasil !<\/li>\r\n                                                                                            <\/ul>\r\n                                                                                                                            <div class=\"gl-about-btn\">\r\n                                                <a class=\"d-flex justify-content-center align-items-center\" href=\"#\">Download PDF <i class=\"fas fa-cloud-download\"><\/i><\/a>\r\n                                            <\/div>\r\n                                                                            <\/div>\r\n                                <\/div>\r\n                            <\/div>         \r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\t\t\r\n    <!-- End of about section\r\n        ============================================= -->\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22bcd79 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"22bcd79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85cfad2\" data-id=\"85cfad2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34bf7b2 elementor-widget elementor-widget-glow-fanfact-v1\" data-id=\"34bf7b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glow-fanfact-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Start of counter section\r\n\t============================================= -->\r\n\t<section id=\"gl-counter-3\" class=\"gl-counter-section-3\">\r\n\t\t<div class=\"container\">\r\n\t\t\t<div class=\"gl-counter-content-3\">\r\n\t\t\t\t<div class=\"row\">\r\n                \t\t\t\t\t<div class=\"col-lg-4 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"gl-counter-inner-item position-relative d-flex align-items-center headline-3\">\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-icon\">\r\n                                <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-award\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M97.12 362.63c-8.69-8.69-4.16-6.24-25.12-11.85-9.51-2.55-17.87-7.45-25.43-13.32L1.2 448.7c-4.39 10.77 3.81 22.47 15.43 22.03l52.69-2.01L105.56 507c8 8.44 22.04 5.81 26.43-4.96l52.05-127.62c-10.84 6.04-22.87 9.58-35.31 9.58-19.5 0-37.82-7.59-51.61-21.37zM382.8 448.7l-45.37-111.24c-7.56 5.88-15.92 10.77-25.43 13.32-21.07 5.64-16.45 3.18-25.12 11.85-13.79 13.78-32.12 21.37-51.62 21.37-12.44 0-24.47-3.55-35.31-9.58L252 502.04c4.39 10.77 18.44 13.4 26.43 4.96l36.25-38.28 52.69 2.01c11.62.44 19.82-11.27 15.43-22.03zM263 340c15.28-15.55 17.03-14.21 38.79-20.14 13.89-3.79 24.75-14.84 28.47-28.98 7.48-28.4 5.54-24.97 25.95-45.75 10.17-10.35 14.14-25.44 10.42-39.58-7.47-28.38-7.48-24.42 0-52.83 3.72-14.14-.25-29.23-10.42-39.58-20.41-20.78-18.47-17.36-25.95-45.75-3.72-14.14-14.58-25.19-28.47-28.98-27.88-7.61-24.52-5.62-44.95-26.41-10.17-10.35-25-14.4-38.89-10.61-27.87 7.6-23.98 7.61-51.9 0-13.89-3.79-28.72.25-38.89 10.61-20.41 20.78-17.05 18.8-44.94 26.41-13.89 3.79-24.75 14.84-28.47 28.98-7.47 28.39-5.54 24.97-25.95 45.75-10.17 10.35-14.15 25.44-10.42 39.58 7.47 28.36 7.48 24.4 0 52.82-3.72 14.14.25 29.23 10.42 39.59 20.41 20.78 18.47 17.35 25.95 45.75 3.72 14.14 14.58 25.19 28.47 28.98C104.6 325.96 106.27 325 121 340c13.23 13.47 33.84 15.88 49.74 5.82a39.676 39.676 0 0 1 42.53 0c15.89 10.06 36.5 7.65 49.73-5.82zM97.66 175.96c0-53.03 42.24-96.02 94.34-96.02s94.34 42.99 94.34 96.02-42.24 96.02-94.34 96.02-94.34-42.99-94.34-96.02z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-text pera-content\">\r\n\t\t\t\t\t\t\t\t<h3><span class=\"odometer\" data-count=\"30\"><\/span>+<\/h3>\r\n\t\t\t\t\t\t\t\t<p>Awards Win<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n                    \t\t\t\t\t<div class=\"col-lg-4 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"gl-counter-inner-item position-relative d-flex align-items-center headline-3\">\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-icon\">\r\n                                <svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-users\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M96 224c35.3 0 64-28.7 64-64s-28.7-64-64-64-64 28.7-64 64 28.7 64 64 64zm448 0c35.3 0 64-28.7 64-64s-28.7-64-64-64-64 28.7-64 64 28.7 64 64 64zm32 32h-64c-17.6 0-33.5 7.1-45.1 18.6 40.3 22.1 68.9 62 75.1 109.4h66c17.7 0 32-14.3 32-32v-32c0-35.3-28.7-64-64-64zm-256 0c61.9 0 112-50.1 112-112S381.9 32 320 32 208 82.1 208 144s50.1 112 112 112zm76.8 32h-8.3c-20.8 10-43.9 16-68.5 16s-47.6-6-68.5-16h-8.3C179.6 288 128 339.6 128 403.2V432c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48v-28.8c0-63.6-51.6-115.2-115.2-115.2zm-223.7-13.4C161.5 263.1 145.6 256 128 256H64c-35.3 0-64 28.7-64 64v32c0 17.7 14.3 32 32 32h65.9c6.3-47.4 34.9-87.3 75.2-109.4z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-text pera-content\">\r\n\t\t\t\t\t\t\t\t<h3><span class=\"odometer\" data-count=\"90\"><\/span>+<\/h3>\r\n\t\t\t\t\t\t\t\t<p>Experience Member<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n                    \t\t\t\t\t<div class=\"col-lg-4 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"gl-counter-inner-item position-relative d-flex align-items-center headline-3\">\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-icon\">\r\n                                <i aria-hidden=\"true\" class=\"flaticon flaticon-satisfaction\"><\/i>\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-text pera-content\">\r\n\t\t\t\t\t\t\t\t<h3><span class=\"odometer\" data-count=\"500\"><\/span>+<\/h3>\r\n\t\t\t\t\t\t\t\t<p>Satisfied Clients<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n                    \t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/section>\t\t\r\n<!-- End of counter section\r\n\t============================================= -->\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b622abd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b622abd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-504c776\" data-id=\"504c776\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ac6a3d elementor-widget elementor-widget-glow-teammember-\" data-id=\"0ac6a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"glow-teammember-.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Start of Team section\r\n\t============================================= -->\r\n\t<section id=\"gl-team-3\" class=\"gl-team-section-3\">\r\n\t\t<div class=\"container\">\r\n            \t\t\t<div class=\"gl-section-title-3 text-center\">\r\n                                    <div class=\"subtitle\">\r\n                        Equipe                    <\/div>\r\n                                \t\t\t\t<h2>\r\n                    Nosso Time\t\t\t\t<\/h2>\r\n                \t\t\t<\/div>\r\n              \r\n\t\t\t<div class=\"gl-team-content-3\">\r\n\t\t\t\t<div class=\"row\">\r\n                                        \t\t\t\t\t<div class=\"col-lg-3 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"gl-team-inner-item-3\">\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-item headline-3\">\r\n\t\t\t\t\t\t\t\t<div class=\"thx-inner-img\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2022\/03\/file-_1_.jpeg\" alt=\"Sobre N\u00f3s\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"thx-inner-text text-center ul-li\">\r\n\t\t\t\t\t\t\t\t\t<h3><a href=\"https:\/\/kferfseguros.com.br\/index.php\/glow_team\/matilda-biscoe\/\">Kelly Fagundes<\/a><\/h3>\r\n                                    \t\t\t\t\t\t\t\t\t    <span>S\u00f3cia Diretora<\/span>\r\n                                                                                                                <div class=\"thx-inner-social d-flex justify-content-center\">\r\n                                                                                            <a href=\"https:\/\/www.facebook.com\/kferfseguros\"><i class=\"fab fa-facebook-f\"><\/i><\/a>\r\n                                                                                            <a href=\"https:\/\/www.instagram.com\/kfrf.seguros\/\"><i class=\"fab fa-instagram-square\"><\/i><\/a>\r\n                                                                                            <a href=\"https:\/\/www.linkedin.com\/%20kellykfrf\"><i class=\"fab fa-linkedin\"><\/i><\/a>\r\n                                                                                    <\/div>\r\n                                    \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n                                        \t\t\t\t\t<div class=\"col-lg-3 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"gl-team-inner-item-3\">\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-item headline-3\">\r\n\t\t\t\t\t\t\t\t<div class=\"thx-inner-img\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2022\/03\/WhatsApp-Image-2024-03-05-at-12.40.52.jpeg\" alt=\"Sobre N\u00f3s\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"thx-inner-text text-center ul-li\">\r\n\t\t\t\t\t\t\t\t\t<h3><a href=\"https:\/\/kferfseguros.com.br\/index.php\/glow_team\/samuel-ewan\/\">Rafael Camargo<\/a><\/h3>\r\n                                    \t\t\t\t\t\t\t\t\t    <span>S\u00f3cio Diretor<\/span>\r\n                                                                                                                <div class=\"thx-inner-social d-flex justify-content-center\">\r\n                                                                                            <a href=\"https:\/\/www.facebook.com\/kferfseguros\"><i class=\"fab fa-facebook-f\"><\/i><\/a>\r\n                                                                                            <a href=\"https:\/\/www.instagram.com\/kfrf.seguros\/\"><i class=\"fab fa-instagram-square\"><\/i><\/a>\r\n                                                                                            <a href=\"#\"><i class=\"\"><\/i><\/a>\r\n                                                                                    <\/div>\r\n                                    \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n                                        \t\t\t\t\t<div class=\"col-lg-3 col-md-6\">\r\n\t\t\t\t\t\t<div class=\"gl-team-inner-item-3\">\r\n\t\t\t\t\t\t\t<div class=\"thx-inner-item headline-3\">\r\n\t\t\t\t\t\t\t\t<div class=\"thx-inner-img\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2022\/03\/file-_2_.jpeg\" alt=\"Sobre N\u00f3s\">\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<div class=\"thx-inner-text text-center ul-li\">\r\n\t\t\t\t\t\t\t\t\t<h3><a href=\"https:\/\/kferfseguros.com.br\/index.php\/glow_team\/madison-grano\/\">Andreia Bonaf\u00e9<\/a><\/h3>\r\n                                    \t\t\t\t\t\t\t\t\t    <span>Compliance Officer jur\u00eddico<\/span>\r\n                                                                                                                <div class=\"thx-inner-social d-flex justify-content-center\">\r\n                                                                                            <a href=\"https:\/\/www.facebook.com\/kferfseguros\"><i class=\"fab fa-facebook-square\"><\/i><\/a>\r\n                                                                                            <a href=\"https:\/\/www.instagram.com\/kfrf.seguros\/\"><i class=\"fab fa-instagram-square\"><\/i><\/a>\r\n                                                                                            <a href=\"#\"><i class=\"\"><\/i><\/a>\r\n                                                                                    <\/div>\r\n                                    \t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n                                        \r\n\t\t\t\t<\/div>\r\n                \t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/section>\t\r\n<!-- End of Team section\r\n\t============================================= -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3956d44 e-flex e-con-boxed e-con e-parent\" data-id=\"3956d44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c1bee6 e-flex e-con-boxed e-con e-child\" data-id=\"3c1bee6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9823692 elementor-widget elementor-widget-spacer\" data-id=\"9823692\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e69d9b elementor-widget elementor-widget-heading\" data-id=\"7e69d9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parceiros \/ Trabalhamos com as mais renomadas Seguradoras do Brasil<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aefb369 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"aefb369\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/por-150x150.png\" alt=\"por\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L2-150x150.png\" alt=\"L2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/mafre-site-png-150x150.png\" alt=\"mafre site png\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L5-150x150.png\" alt=\"L5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L3-150x150.png\" alt=\"L3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L4-150x150.png\" alt=\"L4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L1-150x150.png\" alt=\"L1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L6-150x150.png\" alt=\"L6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L7-150x150.png\" alt=\"L7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L8-150x150.png\" alt=\"L8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L9-150x150.png\" alt=\"L9\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L10-150x150.png\" alt=\"L10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 13\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/kferfseguros.com.br\/wp-content\/uploads\/2024\/03\/L11-150x150.png\" alt=\"L11\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sobre N\u00f3s Nossa Historia KF&amp;RF Seguros A KF &amp; RF Seguros surgiu da uni\u00e3o de profissionais com 18 anos de experi\u00eancia no setor. Nossos fundadores possuem s\u00f3lida viv\u00eancia no mercado financeiro, com passagens por renomados bancos e seguradoras. \u00c1rea Juridica, contamos com uma especialista jur\u00eddica dedicada ao planejamento sucess\u00f3rio e compliance empresarial, o que se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1803","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":20,"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1803\/revisions"}],"predecessor-version":[{"id":4184,"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1803\/revisions\/4184"}],"wp:attachment":[{"href":"https:\/\/kferfseguros.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}